{"id":6952,"count":3,"description":"Reasonable gambling performs a vital function in 1win\u2019s procedures. -","link":"https:\/\/knetradio.livenetstudios.co.za\/index.php\/category\/1win-login-230\/","name":"1win Login 230","slug":"1win-login-230","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/knetradio.livenetstudios.co.za\/index.php\/wp-json\/wp\/v2\/categories\/6952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/knetradio.livenetstudios.co.za\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/knetradio.livenetstudios.co.za\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/knetradio.livenetstudios.co.za\/index.php\/wp-json\/wp\/v2\/posts?categories=6952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}